{"id":8029,"date":"2021-11-16T16:39:12","date_gmt":"2021-11-16T09:39:12","guid":{"rendered":"https:\/\/theplannereducation.com\/home\/?p=8029"},"modified":"2023-12-14T12:59:52","modified_gmt":"2023-12-14T05:59:52","slug":"%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7","status":"publish","type":"post","link":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/","title":{"rendered":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49!"},"content":{"rendered":"<p><img decoding=\"async\" class=\"wp-image-5442 alignnone size-full\" src=\"https:\/\/theplannereducation.com\/home\/wp-content\/uploads\/2021\/11\/web-\u0e2a\u0e2d\u0e1a-GED-\u0e08\u0e1a-\u0e21.6-\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19-\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49.gif\" alt=\"\" width=\"100%\" \/><\/p>\n<p>\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49!<\/p>\n<p>\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32<\/p>\n<ol>\n<li><strong>\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/strong> \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08!<\/li>\n<li><strong>\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19<\/strong> \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/li>\n<li><strong>\u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<\/strong> \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34 GED \u0e44\u0e14\u0e49 \u0e01\u0e47\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49\u0e40\u0e23\u0e47\u0e27 \u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e23\u0e47\u0e27\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e04\u0e34\u0e14\u0e44\u0e27\u0e49\u00a0 \u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e27 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e21\u0e35\u0e40\u0e27\u0e25\u0e32\u0e43\u0e2b\u0e49 passive income \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/li>\n<\/ol>\n<p>\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e1f\u0e41\u0e23\u0e07 \u0e01\u0e23\u0e30\u0e15\u0e37\u0e2d\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e04\u0e19\u0e44\u0e2b\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1d\u0e31\u0e19\u0e2d\u0e31\u0e19\u0e1b\u0e30\u0e17\u0e38\u0e08\u0e19\u0e2b\u0e22\u0e38\u0e14\u0e44\u0e21\u0e48\u0e2d\u0e22\u0e39\u0e48 \u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e40\u0e17\u0e35\u0e22\u0e1a \u0e21.6 \u0e04\u0e37\u0e2d\u0e04\u0e33\u0e15\u0e2d\u0e1a \u0e41\u0e15\u0e48\u0e2b\u0e32\u0e01\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e01\u0e31\u0e07\u0e27\u0e25\u0e27\u0e48\u0e32\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e44\u0e21\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 The Planner \u0e01\u0e47\u0e21\u0e35\u0e04\u0e2d\u0e23\u0e4c\u0e2a Pre-GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e34\u0e27 GED \u0e41\u0e1a\u0e1a\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22!<\/p>\n<div class=\"allcos\" ><a href=\"https:\/\/theplannereducation.com\/home\/courses\/\">\u0e14\u0e39\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/a><\/div>\n<p>\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 GED \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e40\u0e1a\u0e2d\u0e23\u0e4c <a href=\"tel:+66-95-726-2666\" target=\"_blank\" rel=\"noopener\">095-726-2666<\/a><br \/>\u0e2b\u0e23\u0e37\u0e2d LINE: <a href=\"http:\/\/line.me\/ti\/p\/~@theplanner\" target=\"_blank\" rel=\"noopener\">@theplanner<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49! \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08! \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07<a href=\"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/\">[&#8230;]<\/a><\/p>\n","protected":false},"author":56,"featured_media":8030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,78],"tags":[10],"class_list":["post-8029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-ged","tag-ged"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49! \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08! \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"The Planner Education\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\n\t\t<meta name=\"google-site-verification\" content=\"KGFNzLXHKDkivPDW_cR5ImctoKEvClLot_KejlvmFKc\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"The Planner Education - \u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1e\u0e25\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49! - The Planner Education\" \/>\n\t\t<meta property=\"og:description\" content=\"\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49! \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08! \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-11-16T09:39:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-14T05:59:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49! - The Planner Education\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49! \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08! \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#blogposting\",\"name\":\"\\u0e2a\\u0e2d\\u0e1a GED \\u0e04\\u0e27\\u0e49\\u0e32\\u0e27\\u0e38\\u0e12\\u0e34\\u0e08\\u0e1a \\u0e21.6 \\u0e01\\u0e48\\u0e2d\\u0e19\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e19\\u0e21\\u0e31\\u0e19\\u0e14\\u0e35\\u0e41\\u0e1a\\u0e1a\\u0e19\\u0e35\\u0e49! - The Planner Education\",\"headline\":\"\\u0e2a\\u0e2d\\u0e1a GED \\u0e04\\u0e27\\u0e49\\u0e32\\u0e27\\u0e38\\u0e12\\u0e34\\u0e08\\u0e1a \\u0e21.6 \\u0e01\\u0e48\\u0e2d\\u0e19\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e19\\u0e21\\u0e31\\u0e19\\u0e14\\u0e35\\u0e41\\u0e1a\\u0e1a\\u0e19\\u0e35\\u0e49!\",\"author\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/author\\\/lngbl4rmp3wmtoj2xiv2z\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/web-\\u0e2a\\u0e2d\\u0e1a-GED-\\u0e08\\u0e1a-\\u0e21.6-\\u0e01\\u0e48\\u0e2d\\u0e19\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e19-\\u0e21\\u0e31\\u0e19\\u0e14\\u0e35\\u0e41\\u0e1a\\u0e1a\\u0e19\\u0e35\\u0e49.gif\",\"width\":825,\"height\":422},\"datePublished\":\"2021-11-16T16:39:12+07:00\",\"dateModified\":\"2023-12-14T12:59:52+07:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#webpage\"},\"articleSection\":\"Blog, GED, GED\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/theplannereducation.com\\\/home\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/category\\\/blog\\\/ged\\\/#listItem\",\"name\":\"GED\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/category\\\/blog\\\/ged\\\/#listItem\",\"position\":3,\"name\":\"GED\",\"item\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/category\\\/blog\\\/ged\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#listItem\",\"name\":\"\\u0e2a\\u0e2d\\u0e1a GED \\u0e04\\u0e27\\u0e49\\u0e32\\u0e27\\u0e38\\u0e12\\u0e34\\u0e08\\u0e1a \\u0e21.6 \\u0e01\\u0e48\\u0e2d\\u0e19\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e19\\u0e21\\u0e31\\u0e19\\u0e14\\u0e35\\u0e41\\u0e1a\\u0e1a\\u0e19\\u0e35\\u0e49!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#listItem\",\"position\":4,\"name\":\"\\u0e2a\\u0e2d\\u0e1a GED \\u0e04\\u0e27\\u0e49\\u0e32\\u0e27\\u0e38\\u0e12\\u0e34\\u0e08\\u0e1a \\u0e21.6 \\u0e01\\u0e48\\u0e2d\\u0e19\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e19\\u0e21\\u0e31\\u0e19\\u0e14\\u0e35\\u0e41\\u0e1a\\u0e1a\\u0e19\\u0e35\\u0e49!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/category\\\/blog\\\/ged\\\/#listItem\",\"name\":\"GED\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/#organization\",\"name\":\"The Planner Education\",\"description\":\"\\u0e40\\u0e14\\u0e2d\\u0e30 \\u0e41\\u0e1e\\u0e25\\u0e19\\u0e40\\u0e19\\u0e2d\\u0e23\\u0e4c \\u0e40\\u0e2d\\u0e14\\u0e14\\u0e39\\u0e40\\u0e04\\u0e0a\\u0e31\\u0e48\\u0e19\",\"url\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/author\\\/lngbl4rmp3wmtoj2xiv2z\\\/#author\",\"url\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/author\\\/lngbl4rmp3wmtoj2xiv2z\\\/\",\"name\":\"The Planner Education\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f44bba12cbebdf0c1e927fae0911b680b570de19187caef72b023da74fb5b740?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"The Planner Education\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#webpage\",\"url\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/\",\"name\":\"\\u0e2a\\u0e2d\\u0e1a GED \\u0e04\\u0e27\\u0e49\\u0e32\\u0e27\\u0e38\\u0e12\\u0e34\\u0e08\\u0e1a \\u0e21.6 \\u0e01\\u0e48\\u0e2d\\u0e19\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e19\\u0e21\\u0e31\\u0e19\\u0e14\\u0e35\\u0e41\\u0e1a\\u0e1a\\u0e19\\u0e35\\u0e49! - The Planner Education\",\"description\":\"\\u0e23\\u0e39\\u0e49\\u0e21\\u0e31\\u0e49\\u0e22\\u0e27\\u0e48\\u0e32\\u0e40\\u0e23\\u0e32\\u0e44\\u0e21\\u0e48\\u0e08\\u0e33\\u0e40\\u0e1b\\u0e47\\u0e19\\u0e15\\u0e49\\u0e2d\\u0e07\\u0e23\\u0e2d\\u0e43\\u0e2b\\u0e49\\u0e08\\u0e1a \\u0e21.6 \\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e44\\u0e1b\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19\\u0e15\\u0e48\\u0e2d\\u0e21\\u0e2b\\u0e32\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22 \\u0e40\\u0e1e\\u0e23\\u0e32\\u0e30\\u0e40\\u0e23\\u0e32\\u0e2a\\u0e32\\u0e21\\u0e32\\u0e23\\u0e16\\u0e2a\\u0e2d\\u0e1a GED \\u0e0b\\u0e36\\u0e48\\u0e07\\u0e40\\u0e1b\\u0e47\\u0e19\\u0e27\\u0e38\\u0e12\\u0e34\\u0e01\\u0e32\\u0e23\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e17\\u0e35\\u0e48\\u0e40\\u0e17\\u0e35\\u0e22\\u0e1a\\u0e40\\u0e17\\u0e48\\u0e32\\u0e21\\u0e31\\u0e18\\u0e22\\u0e21\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e0a\\u0e31\\u0e49\\u0e19\\u0e1b\\u0e35\\u0e17\\u0e35\\u0e48 6 \\u0e2d\\u0e22\\u0e48\\u0e32\\u0e07\\u0e17\\u0e35\\u0e48\\u0e1e\\u0e2d\\u0e08\\u0e30\\u0e17\\u0e23\\u0e32\\u0e1a\\u0e01\\u0e31\\u0e19\\u0e41\\u0e25\\u0e49\\u0e27\\u0e27\\u0e48\\u0e32\\u0e02\\u0e49\\u0e2d\\u0e2a\\u0e2d\\u0e1a GED \\u0e40\\u0e1b\\u0e47\\u0e19\\u0e01\\u0e32\\u0e23\\u0e2a\\u0e2d\\u0e1a\\u0e40\\u0e17\\u0e35\\u0e22\\u0e1a\\u0e27\\u0e38\\u0e12\\u0e34\\u0e01\\u0e32\\u0e23\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e15\\u0e2d\\u0e19\\u0e1b\\u0e25\\u0e32\\u0e22\\u0e43\\u0e19\\u0e23\\u0e30\\u0e1a\\u0e1a\\u0e2d\\u0e40\\u0e21\\u0e23\\u0e34\\u0e01\\u0e31\\u0e19 \\u0e41\\u0e25\\u0e30\\u0e44\\u0e14\\u0e49\\u0e23\\u0e31\\u0e1a\\u0e01\\u0e32\\u0e23\\u0e23\\u0e31\\u0e1a\\u0e23\\u0e2d\\u0e07\\u0e08\\u0e32\\u0e01\\u0e17\\u0e31\\u0e48\\u0e27\\u0e42\\u0e25\\u0e01 \\u0e2a\\u0e32\\u0e21\\u0e32\\u0e23\\u0e16\\u0e22\\u0e37\\u0e48\\u0e19\\u0e27\\u0e38\\u0e12\\u0e34 GED \\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e15\\u0e48\\u0e2d\\u0e43\\u0e19\\u0e23\\u0e30\\u0e14\\u0e31\\u0e1a\\u0e21\\u0e2b\\u0e32\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e17\\u0e31\\u0e49\\u0e07\\u0e43\\u0e19\\u0e44\\u0e17\\u0e22\\u0e41\\u0e25\\u0e30\\u0e15\\u0e48\\u0e32\\u0e07\\u0e1b\\u0e23\\u0e30\\u0e40\\u0e17\\u0e28 \\u0e23\\u0e27\\u0e21\\u0e16\\u0e36\\u0e07\\u0e22\\u0e37\\u0e48\\u0e19\\u0e2a\\u0e21\\u0e31\\u0e04\\u0e23\\u0e07\\u0e32\\u0e19\\u0e01\\u0e47\\u0e22\\u0e31\\u0e07\\u0e44\\u0e14\\u0e49! \\u0e43\\u0e19\\u0e2a\\u0e16\\u0e32\\u0e19\\u0e01\\u0e32\\u0e23\\u0e13\\u0e4c\\u0e1a\\u0e49\\u0e32\\u0e19\\u0e40\\u0e21\\u0e37\\u0e2d\\u0e07\\u0e17\\u0e35\\u0e48\\u0e21\\u0e35\\u0e42\\u0e23\\u0e04\\u0e23\\u0e30\\u0e1a\\u0e32\\u0e14\\u0e2d\\u0e22\\u0e48\\u0e32\\u0e07 COVID-19 \\u0e41\\u0e1a\\u0e1a\\u0e19\\u0e35\\u0e49 \\u0e17\\u0e33\\u0e43\\u0e2b\\u0e49\\u0e19\\u0e49\\u0e2d\\u0e07\\u0e46 \\u0e15\\u0e49\\u0e2d\\u0e07\\u0e40\\u0e2a\\u0e35\\u0e22\\u0e42\\u0e2d\\u0e01\\u0e32\\u0e2a\\u0e43\\u0e19\\u0e2b\\u0e25\\u0e32\\u0e22\\u0e46 \\u0e40\\u0e23\\u0e37\\u0e48\\u0e2d\\u0e07 \\u0e41\\u0e25\\u0e30\\u0e40\\u0e14\\u0e32\\u0e27\\u0e48\\u0e32\\u0e19\\u0e49\\u0e2d\\u0e07\\u0e46 \\u0e2b\\u0e25\\u0e32\\u0e22\\u0e04\\u0e19\\u0e2d\\u0e32\\u0e08\\u0e08\\u0e30\\u0e01\\u0e33\\u0e25\\u0e31\\u0e07\\u0e04\\u0e23\\u0e38\\u0e48\\u0e19\\u0e04\\u0e34\\u0e14\\u0e17\\u0e35\\u0e48\\u0e08\\u0e30\\u0e15\\u0e34\\u0e27 GED \\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e2a\\u0e2d\\u0e1a\\u0e08\\u0e1a\\u0e01\\u0e32\\u0e23\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e0a\\u0e31\\u0e49\\u0e19\\u0e21\\u0e31\\u0e18\\u0e22\\u0e21\\u0e1b\\u0e25\\u0e32\\u0e22\\u0e43\\u0e2b\\u0e49\\u0e23\\u0e39\\u0e49\\u0e41\\u0e25\\u0e49\\u0e27\\u0e23\\u0e39\\u0e49\\u0e23\\u0e2d\\u0e14\\u0e01\\u0e31\\u0e19\\u0e44\\u0e1b \\u0e07\\u0e31\\u0e49\\u0e19\\u0e40\\u0e23\\u0e32\\u0e21\\u0e32\\u0e14\\u0e39\\u0e02\\u0e49\\u0e2d\\u0e14\\u0e35\\u0e02\\u0e2d\\u0e07\\u0e01\\u0e32\\u0e23\\u0e2a\\u0e2d\\u0e1a GED \\u0e01\\u0e31\\u0e19\\u0e14\\u0e35\\u0e01\\u0e27\\u0e48\\u0e32 \\u0e21\\u0e31\\u0e48\\u0e19\\u0e43\\u0e08\\u0e43\\u0e19\\u0e15\\u0e31\\u0e27\\u0e40\\u0e2d\\u0e07\\u0e21\\u0e32\\u0e01\\u0e02\\u0e36\\u0e49\\u0e19 \\u0e40\\u0e1e\\u0e23\\u0e32\\u0e30\\u0e01\\u0e32\\u0e23\\u0e17\\u0e33\\u0e02\\u0e49\\u0e2d\\u0e2a\\u0e2d\\u0e1a GED \\u0e19\\u0e31\\u0e49\\u0e19\\u0e44\\u0e21\\u0e48\\u0e07\\u0e48\\u0e32\\u0e22 \\u0e21\\u0e35\\u0e17\\u0e31\\u0e49\\u0e07 Math, Science, Social Studies \\u0e41\\u0e25\\u0e30 RLA \\u0e41\\u0e15\\u0e48\\u0e25\\u0e30\\u0e27\\u0e34\\u0e0a\\u0e32\\u0e15\\u0e49\\u0e2d\\u0e07\\u0e43\\u0e0a\\u0e49\\u0e17\\u0e31\\u0e01\\u0e29\\u0e30\\u0e04\\u0e27\\u0e32\\u0e21\\u0e23\\u0e39\\u0e49\\u0e44\\u0e21\\u0e48\\u0e41\\u0e1e\\u0e49\\u0e01\\u0e31\\u0e1a\\u0e01\\u0e32\\u0e23\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19\\u0e43\\u0e19\\u0e42\\u0e23\\u0e07\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19\\u0e40\\u0e25\\u0e22 \\u0e09\\u0e30\\u0e19\\u0e31\\u0e49\\u0e19\\u0e01\\u0e32\\u0e23\\u0e17\\u0e35\\u0e48\\u0e40\\u0e23\\u0e32\\u0e2a\\u0e32\\u0e21\\u0e32\\u0e23\\u0e16\\u0e2a\\u0e2d\\u0e1a\\u0e1c\\u0e48\\u0e32\\u0e19\\u0e44\\u0e14\\u0e49\\u0e2a\\u0e33\\u0e40\\u0e23\\u0e47\\u0e08\\u0e16\\u0e37\\u0e2d\\u0e27\\u0e48\\u0e32\\u0e21\\u0e35\\u0e04\\u0e27\\u0e32\\u0e21\\u0e23\\u0e39\\u0e49\\u0e21\\u0e32\\u0e01\\u0e1e\\u0e2d \\u0e41\\u0e25\\u0e30\\u0e01\\u0e32\\u0e23\\u0e17\\u0e35\\u0e48\\u0e40\\u0e23\\u0e32\\u0e2a\\u0e2d\\u0e1a GED \\u0e1c\\u0e48\\u0e32\\u0e19\\u0e19\\u0e35\\u0e48\\u0e41\\u0e2b\\u0e25\\u0e30 \\u0e17\\u0e33\\u0e43\\u0e2b\\u0e49\\u0e40\\u0e23\\u0e32\\u0e21\\u0e35\\u0e04\\u0e27\\u0e32\\u0e21\\u0e21\\u0e31\\u0e48\\u0e19\\u0e43\\u0e08\\u0e43\\u0e19\\u0e15\\u0e31\\u0e27\\u0e40\\u0e2d\\u0e07 \\u0e40\\u0e1e\\u0e23\\u0e32\\u0e30\\u0e40\\u0e23\\u0e32\\u0e44\\u0e14\\u0e49\\u0e17\\u0e33\\u0e15\\u0e32\\u0e21\\u0e40\\u0e1b\\u0e49\\u0e32\\u0e2b\\u0e21\\u0e32\\u0e22\\u0e44\\u0e14\\u0e49\\u0e2a\\u0e33\\u0e40\\u0e23\\u0e47\\u0e08! \\u0e40\\u0e23\\u0e35\\u0e22\\u0e19\\u0e15\\u0e48\\u0e2d\\u0e21\\u0e2b\\u0e32\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e40\\u0e23\\u0e47\\u0e27\\u0e02\\u0e36\\u0e49\\u0e19 \\u0e40\\u0e1e\\u0e23\\u0e32\\u0e30\\u0e27\\u0e38\\u0e12\\u0e34 GED \\u0e04\\u0e37\\u0e2d\\u0e27\\u0e38\\u0e12\\u0e34\\u0e01\\u0e32\\u0e23\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e40\\u0e17\\u0e35\\u0e22\\u0e1a\\u0e40\\u0e17\\u0e48\\u0e32\\u0e23\\u0e30\\u0e14\\u0e31\\u0e1a\\u0e0a\\u0e31\\u0e49\\u0e19\\u0e21\\u0e31\\u0e18\\u0e22\\u0e21\\u0e28\\u0e36\\u0e01\\u0e29\\u0e32\\u0e15\\u0e2d\\u0e19\\u0e1b\\u0e25\\u0e32\\u0e22 \\u0e21\\u0e35\\u0e04\\u0e27\\u0e32\\u0e21\\u0e23\\u0e39\\u0e49\\u0e40\\u0e17\\u0e35\\u0e22\\u0e1a\\u0e40\\u0e17\\u0e48\\u0e32\\u0e19\\u0e31\\u0e01\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19\\u0e43\\u0e19\\u0e23\\u0e30\\u0e1a\\u0e1a\\u0e42\\u0e23\\u0e07\\u0e40\\u0e23\\u0e35\\u0e22\\u0e19 \\u0e41\\u0e25\\u0e30\\u0e41\\u0e19\\u0e48\\u0e19\\u0e2d\\u0e19\\u0e27\\u0e48\\u0e32\\u0e43\\u0e0a\\u0e49\\u0e22\\u0e37\\u0e48\\u0e19\\u0e2a\\u0e21\\u0e31\\u0e04\\u0e23\\u0e2a\\u0e2d\\u0e1a\\u0e40\\u0e02\\u0e49\\u0e32\\u0e21\\u0e2b\\u0e32\\u0e27\\u0e34\\u0e17\\u0e22\\u0e32\\u0e25\\u0e31\\u0e22\\u0e44\\u0e14\\u0e49\\u0e40\\u0e25\\u0e22 \\u0e19\\u0e2d\\u0e01\\u0e08\\u0e32\\u0e01\\u0e19\\u0e31\\u0e49\\u0e19\\u0e22\\u0e31\\u0e07\\u0e2a\\u0e32\\u0e21\\u0e32\\u0e23\\u0e16\\u0e43\\u0e0a\\u0e49\\u0e43\\u0e19\\u0e01\\u0e32\\u0e23\\u0e2a\\u0e21\\u0e31\\u0e04\\u0e23\\u0e07\\u0e32\\u0e19\\u0e44\\u0e14\\u0e49\\u0e2d\\u0e35\\u0e01\\u0e14\\u0e49\\u0e27\\u0e22 \\u0e40\\u0e2d\\u0e32\\u0e40\\u0e27\\u0e25\\u0e32\\u0e44\\u0e1b\\u0e2b\\u0e32\\u0e23\\u0e32\\u0e22\\u0e44\\u0e14\\u0e49\\u0e43\\u0e2b\\u0e49\\u0e21\\u0e32\\u0e01\\u0e02\\u0e36\\u0e49\\u0e19 \\u0e2a\\u0e37\\u0e1a\\u0e40\\u0e19\\u0e37\\u0e48\\u0e2d\\u0e07\\u0e08\\u0e32\\u0e01\\u0e02\\u0e49\\u0e2d\\u0e2a\\u0e2d\\u0e07\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/author\\\/lngbl4rmp3wmtoj2xiv2z\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/author\\\/lngbl4rmp3wmtoj2xiv2z\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/web-\\u0e2a\\u0e2d\\u0e1a-GED-\\u0e08\\u0e1a-\\u0e21.6-\\u0e01\\u0e48\\u0e2d\\u0e19\\u0e40\\u0e1e\\u0e37\\u0e48\\u0e2d\\u0e19-\\u0e21\\u0e31\\u0e19\\u0e14\\u0e35\\u0e41\\u0e1a\\u0e1a\\u0e19\\u0e35\\u0e49.gif\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#mainImage\",\"width\":825,\"height\":422},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/blog\\\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\\\/#mainImage\"},\"datePublished\":\"2021-11-16T16:39:12+07:00\",\"dateModified\":\"2023-12-14T12:59:52+07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/#website\",\"url\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/\",\"name\":\"The Planner Education\",\"description\":\"\\u0e40\\u0e14\\u0e2d\\u0e30 \\u0e41\\u0e1e\\u0e25\\u0e19\\u0e40\\u0e19\\u0e2d\\u0e23\\u0e4c \\u0e40\\u0e2d\\u0e14\\u0e14\\u0e39\\u0e40\\u0e04\\u0e0a\\u0e31\\u0e48\\u0e19\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/theplannereducation.com\\\/home\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49! - The Planner Education","description":"\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49! \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08! \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07","canonical_url":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;meta name=\"google-site-verification\" content=\"KGFNzLXHKDkivPDW_cR5ImctoKEvClLot_KejlvmFKc\" \/&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#blogposting","name":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49! - The Planner Education","headline":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49!","author":{"@id":"https:\/\/theplannereducation.com\/home\/author\/lngbl4rmp3wmtoj2xiv2z\/#author"},"publisher":{"@id":"https:\/\/theplannereducation.com\/home\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/theplannereducation.com\/home\/wp-content\/uploads\/2021\/11\/web-\u0e2a\u0e2d\u0e1a-GED-\u0e08\u0e1a-\u0e21.6-\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19-\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49.gif","width":825,"height":422},"datePublished":"2021-11-16T16:39:12+07:00","dateModified":"2023-12-14T12:59:52+07:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#webpage"},"isPartOf":{"@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#webpage"},"articleSection":"Blog, GED, GED"},{"@type":"BreadcrumbList","@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home#listItem","position":1,"name":"Home","item":"https:\/\/theplannereducation.com\/home","nextItem":{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/theplannereducation.com\/home\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home\/category\/blog\/ged\/#listItem","name":"GED"},"previousItem":{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home\/category\/blog\/ged\/#listItem","position":3,"name":"GED","item":"https:\/\/theplannereducation.com\/home\/category\/blog\/ged\/","nextItem":{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#listItem","name":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#listItem","position":4,"name":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49!","previousItem":{"@type":"ListItem","@id":"https:\/\/theplannereducation.com\/home\/category\/blog\/ged\/#listItem","name":"GED"}}]},{"@type":"Organization","@id":"https:\/\/theplannereducation.com\/home\/#organization","name":"The Planner Education","description":"\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1e\u0e25\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19","url":"https:\/\/theplannereducation.com\/home\/"},{"@type":"Person","@id":"https:\/\/theplannereducation.com\/home\/author\/lngbl4rmp3wmtoj2xiv2z\/#author","url":"https:\/\/theplannereducation.com\/home\/author\/lngbl4rmp3wmtoj2xiv2z\/","name":"The Planner Education","image":{"@type":"ImageObject","@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f44bba12cbebdf0c1e927fae0911b680b570de19187caef72b023da74fb5b740?s=96&d=mm&r=g","width":96,"height":96,"caption":"The Planner Education"}},{"@type":"WebPage","@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#webpage","url":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/","name":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49! - The Planner Education","description":"\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49! \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08! \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/theplannereducation.com\/home\/#website"},"breadcrumb":{"@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#breadcrumblist"},"author":{"@id":"https:\/\/theplannereducation.com\/home\/author\/lngbl4rmp3wmtoj2xiv2z\/#author"},"creator":{"@id":"https:\/\/theplannereducation.com\/home\/author\/lngbl4rmp3wmtoj2xiv2z\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/theplannereducation.com\/home\/wp-content\/uploads\/2021\/11\/web-\u0e2a\u0e2d\u0e1a-GED-\u0e08\u0e1a-\u0e21.6-\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19-\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49.gif","@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#mainImage","width":825,"height":422},"primaryImageOfPage":{"@id":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/#mainImage"},"datePublished":"2021-11-16T16:39:12+07:00","dateModified":"2023-12-14T12:59:52+07:00"},{"@type":"WebSite","@id":"https:\/\/theplannereducation.com\/home\/#website","url":"https:\/\/theplannereducation.com\/home\/","name":"The Planner Education","description":"\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1e\u0e25\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19","inLanguage":"en-US","publisher":{"@id":"https:\/\/theplannereducation.com\/home\/#organization"}}]},"og:locale":"en_US","og:site_name":"The Planner Education - \u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1e\u0e25\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19","og:type":"article","og:title":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49! - The Planner Education","og:description":"\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49! \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08! \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07","og:url":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/","article:published_time":"2021-11-16T09:39:12+00:00","article:modified_time":"2023-12-14T05:59:52+00:00","twitter:card":"summary_large_image","twitter:title":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49! - The Planner Education","twitter:description":"\u0e23\u0e39\u0e49\u0e21\u0e31\u0e49\u0e22\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e08\u0e1a \u0e21.6 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a GED \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e08\u0e30\u0e17\u0e23\u0e32\u0e1a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e27\u0e38\u0e12\u0e34 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49! \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e23\u0e04\u0e23\u0e30\u0e1a\u0e32\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07 COVID-19 \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e32\u0e27\u0e48\u0e32\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e08\u0e30\u0e15\u0e34\u0e27 GED \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e08\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e1b\u0e25\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27\u0e23\u0e39\u0e49\u0e23\u0e2d\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e07\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e21\u0e32\u0e14\u0e39\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a GED \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a GED \u0e19\u0e31\u0e49\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07 Math, Science, Social Studies \u0e41\u0e25\u0e30 RLA \u0e41\u0e15\u0e48\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e01\u0e29\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e25\u0e22 \u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e21\u0e32\u0e01\u0e1e\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e2d\u0e1a GED \u0e1c\u0e48\u0e32\u0e19\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08! \u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e23\u0e47\u0e27\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e38\u0e12\u0e34 GED \u0e04\u0e37\u0e2d\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e22\u0e37\u0e48\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e27\u0e25\u0e32\u0e44\u0e1b\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e07"},"aioseo_meta_data":{"post_id":"8029","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":true,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-05-27 00:07:15","updated":"2025-05-27 00:07:15","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/theplannereducation.com\/home\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/theplannereducation.com\/home\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/theplannereducation.com\/home\/category\/blog\/ged\/\" title=\"GED\">GED<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/theplannereducation.com\/home"},{"label":"Blog","link":"https:\/\/theplannereducation.com\/home\/category\/blog\/"},{"label":"GED","link":"https:\/\/theplannereducation.com\/home\/category\/blog\/ged\/"},{"label":"\u0e2a\u0e2d\u0e1a GED \u0e04\u0e27\u0e49\u0e32\u0e27\u0e38\u0e12\u0e34\u0e08\u0e1a \u0e21.6 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e14\u0e35\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49!","link":"https:\/\/theplannereducation.com\/home\/blog\/%e0%b8%aa%e0%b8%ad%e0%b8%9a-ged-%e0%b8%84%e0%b8%a7%e0%b9%89%e0%b8%b2%e0%b8%a7%e0%b8%b8%e0%b8%92%e0%b8%b4%e0%b8%88%e0%b8%9a-%e0%b8%a1-6-%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b9%80%e0%b8%9e%e0%b8%b7\/"}],"_links":{"self":[{"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/posts\/8029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/comments?post=8029"}],"version-history":[{"count":0,"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/posts\/8029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/media\/8030"}],"wp:attachment":[{"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/media?parent=8029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/categories?post=8029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theplannereducation.com\/home\/wp-json\/wp\/v2\/tags?post=8029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}